{"id":818,"date":"2020-09-24T09:23:15","date_gmt":"2020-09-24T09:23:15","guid":{"rendered":"https:\/\/diatip.com\/home\/"},"modified":"2025-05-21T08:58:59","modified_gmt":"2025-05-21T08:58:59","slug":"home","status":"publish","type":"page","link":"https:\/\/www.diatip.com\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-818\" data-postid=\"818\" class=\"themify_builder_content themify_builder_content-818 themify_builder tf_clear\">\n                    <div  data-css_id=\"peye229\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth tb_peye229 tb_first tf_w\">\n            <span  class=\"builder_row_cover tf_abs\" data-lazy=\"1\"><\/span><span class=\"tb_row_frame_wrap tf_overflow tf_abs\" data-lazy=\"1\"><span class=\"tb_row_frame tb_row_frame_bottom  tf_abs tf_hide tf_overflow tf_w\"><\/span><\/span>            <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_3fpd231 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_h4hh231   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h4 style=\"text-align: center;\">Diatip\u2122 has everything you need for a successful re-tipping work:<\/h4>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_aj86232   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h4 style=\"text-align: center;\">Equipment, Brazing Magnets, Auxiliaries and Instructions.\u00a0<\/h4>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_t2oo934 tf_w\">\n            <span class=\"tb_row_frame_wrap tf_overflow tf_abs\" data-lazy=\"1\"><span class=\"tb_row_frame tb_row_frame_bottom  tf_abs tf_hide tf_overflow tf_w\"><\/span><\/span>            <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_yeek937 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_txst938   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h1 style=\"text-align: center;\">Bienvenue sur Diatip<\/h1>\n<p style=\"text-align: center;\">Diatip a tout ce dont vous avez besoin pour une r\u00e9paration de pointe r\u00e9ussie : \u00e9quipements, aimants de brasage, auxiliaires et instructions. Plus de 30 ans d&rsquo;exp\u00e9rience dans les \u00e9quipements de r\u00e9paration de pointe des couronnes \u00e0 diamant et autres machines de r\u00e9paration des outils diamant\u00e9s. Depuis le d\u00e9but, plus de 1500 unit\u00e9s ont \u00e9t\u00e9 vendues \u00e0 des clients satisfaits dans le monde entier. Qualit\u00e9 sup\u00e9rieure av\u00e9r\u00e9e \u2013 les premi\u00e8res machines vendues sont encore utilis\u00e9es. Service et support complets \u2013 auxiliaires, pi\u00e8ces de rechange et pi\u00e8ces d&rsquo;usure en stock.<\/p>    <\/div>\n<\/div>\n<!-- \/module text -->        <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_4ixf673\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column col-full tb_ksa7673 first\">\n                            <\/div>\n                    <\/div>\n                <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_osiw938\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column col-full tb_wlz7938 first\">\n                    <!-- module video -->\n<div  class=\"module module-video tb_p75g939 video-top  video-autoplay\" data-lazy=\"1\">\n                    <div class=\"video-wrap-outer\" style=\"max-width:100%\">\n            <div class=\"video-wrap tf_rel tf_overflow\">\n                                    <noscript><iframe data-no-script src=\"https:\/\/www.youtube.com\/embed\/WQGUW7cYSM4?pip=1&#038;playsinline=1&#038;autoplay=1\" allow=\"accelerometer;encrypted-media;gyroscope;picture-in-picture;fullscreen;autoplay\" class=\"tf_abs tf_w tf_h\"><\/iframe><\/noscript>\n                                <\/div>\n            <!-- \/video-wrap -->\n        <\/div>\n        <!-- \/video-wrap-outer -->\n            <\/div>\n<!-- module divider -->\n<div  class=\"module tf_mw module-divider tb_562f939 solid   \" style=\"border-width: 1px;border-color: #ffffff;margin-top: 15px;margin-bottom: 0px;\" data-lazy=\"1\">\n    <\/div>\n<!-- \/module divider -->\n<!-- module box -->\n<div  class=\"module module-box tb_f0s9845 \" data-lazy=\"1\">\n    <div class=\"module-box-content ui rounded pink\">\n                <div class=\"tb_text_wrap\"><h4 style=\"text-align: center;\"><strong>MAINTENANT!<\/strong> 10\u00a0% de r\u00e9duction suppl\u00e9mentaire sur votre premi\u00e8re commande.<\/h4><\/div>\n    <\/div>\n<\/div>\n<!-- \/module box -->\n        <\/div>\n                    <\/div>\n                <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_o6gb934 tf_w\">\n            <span class=\"tb_row_frame_wrap tf_overflow tf_abs\" data-lazy=\"1\"><span class=\"tb_row_frame tb_row_frame_bottom  tf_abs tf_hide tf_overflow tf_w\"><\/span><\/span>            <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_1wa0940 first\">\n                            <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_ty89941\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column col-full tb_t5di941 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_le1u941   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h2 style=\"text-align: center;\">Machines \u00e0 la mani\u00e8re de Diatip<\/h2>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module divider -->\n<div  class=\"module tf_mw module-divider tb_djlw941 solid   \" style=\"border-width: 1px;border-color: #f2f2f2;margin-top: 30px;margin-bottom: 30px;\" data-lazy=\"1\">\n    <\/div>\n<!-- \/module divider -->\n<!-- module template_part -->\n<div  class=\"module module-layout-part tb_l472586 \">\n    <div class=\"tb_layout_part_wrap tf_w\"><!--themify_builder_content-->\n    <div  class=\"themify_builder_content themify_builder_content-1297 themify_builder not_editable_builder in_the_loop\" data-postid=\"1297\">\n                        <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_mgaj540 tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_siic542 first\">\n                            <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_middle gutter-none tb_col_count_4 tb_nynv543\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column col4-1 tb_1097543 first\">\n                    <!-- module image -->\n<div  class=\"module module-image tb_z7o8544 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/diatip.com\/wp-content\/uploads\/2014\/06\/CD-7-28-Automatic.jpg\" width=\"300\" height=\"250\" title=\"Accueil\" alt=\"Accueil\">    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column sub_column col4-1 tb_gs8u544\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_w5ef544   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h2>Machines<\/h2>\n<p>L\u2019\u00e9quipement Diatip coupe rapidement et silencieusement pour une division parfaite du segment, un brasage plus simple de nouveaux segments et plus de perte de segment.<\/p>\n    <\/div>\n<\/div>\n<!-- \/module text --><!-- module buttons -->\n<div  class=\"module module-buttons tb_ni4a544 buttons-horizontal solid  large squared\" data-lazy=\"1\">\n        <div class=\"module-buttons-item tf_in_flx\">\n                        <a href=\"https:\/\/diatip.com\/fr\/des-produits\/machines\/\" class=\"ui builder_button tf_in_flx blue\" >\n                                                Voir les machines                                        <\/a>\n                <\/div>\n            <\/div>\n<!-- \/module buttons -->\n<!-- module divider -->\n<div  class=\"module tf_mw module-divider tb_ydmr545 solid    hide-desktop hide-tablet_landscape\" style=\"border-width: 1px;border-color: #0d00bf;margin-top: 30px;\" data-lazy=\"1\">\n    <\/div>\n<!-- \/module divider -->\n        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column sub_column col4-1 tb_ss3l545\">\n                    <!-- module image -->\n<div  class=\"module module-image tb_2r9c545 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/diatip.com\/wp-content\/uploads\/2015\/02\/Magnets-new.jpg\" width=\"300\" height=\"250\" title=\"Accueil\" alt=\"Accueil\">    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column sub_column col4-1 tb_fcmo545 last\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_j54a546   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h2>Aimants<\/h2><p>Employez nos aimants JM ou nos aimants \u00e0 flux r\u00e9sistants pour des d\u00e9pouilles lat\u00e9rales et un positionnement pr\u00e9cis des segments \u00e0 diamant pendant le brasage de la couronne.<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module buttons -->\n<div  class=\"module module-buttons tb_t4h5546 buttons-horizontal solid  large squared\" data-lazy=\"1\">\n        <div class=\"module-buttons-item tf_in_flx\">\n                        <a href=\"http:\/\/diatip.com\/products\/magnets\" class=\"ui builder_button tf_in_flx blue\" >\n                                                Voir les aimants                                        <\/a>\n                <\/div>\n            <\/div>\n<!-- \/module buttons -->\n<!-- module divider -->\n<div  class=\"module tf_mw module-divider tb_9yjj546 solid    hide-desktop hide-tablet_landscape\" style=\"border-width: 1px;border-color: #0d00bf;margin-top: 30px;\" data-lazy=\"1\">\n    <\/div>\n<!-- \/module divider -->\n        <\/div>\n                    <\/div>\n                <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_middle gutter-none tb_col_count_4 tb_m2ju547\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column col4-1 tb_as22547 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_ku77547   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h2>Argent et Flux<\/h2><p>S\u00e9lectionn\u00e9 pour un brasage facile et s\u00fbr.<br \/>Le prix de l\u2019argent varie selon le prix du march\u00e9.<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module buttons -->\n<div  class=\"module module-buttons tb_m6n3547 buttons-horizontal solid  large squared\" data-lazy=\"1\">\n        <div class=\"module-buttons-item tf_in_flx\">\n                        <a href=\"https:\/\/diatip.com\/fr\/des-produits\/argent-et-flux\/\" class=\"ui builder_button tf_in_flx blue\" >\n                                                Voir les argent et flux                                        <\/a>\n                <\/div>\n            <\/div>\n<!-- \/module buttons -->\n<!-- module divider -->\n<div  class=\"module tf_mw module-divider tb_st5k129 solid    hide-desktop hide-tablet_landscape\" style=\"border-width: 1px;border-color: #0d00bf;margin-top: 30px;\" data-lazy=\"1\">\n    <\/div>\n<!-- \/module divider -->\n        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column sub_column col4-1 tb_az69548\">\n                    <!-- module image -->\n<div  class=\"module module-image tb_dbq5548 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/diatip.com\/wp-content\/uploads\/2015\/02\/Siler-Flux-new.jpg\" width=\"300\" height=\"250\" title=\"Accueil\" alt=\"Accueil\">    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column sub_column col4-1 tb_gxc1548\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_axx1548   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h2>Accessoires<\/h2><p>Nous fournissons de nombreux accessoires qui peuvent \u00e9tendre votre utilisation de votre \u00e9quipement; Outils de coupe, adaptateurs, extensions et llames.<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module buttons -->\n<div  class=\"module module-buttons tb_4m0k549 buttons-horizontal solid  large squared\" data-lazy=\"1\">\n        <div class=\"module-buttons-item tf_in_flx\">\n                        <a href=\"https:\/\/diatip.com\/fr\/des-produits\/accessoires\/\" class=\"ui builder_button tf_in_flx blue\" >\n                                                Voir les accessoires                                        <\/a>\n                <\/div>\n            <\/div>\n<!-- \/module buttons -->\n<!-- module divider -->\n<div  class=\"module tf_mw module-divider tb_rulk549 solid    hide-desktop hide-tablet_landscape\" style=\"border-width: 1px;border-color: #0d00bf;margin-top: 30px;\" data-lazy=\"1\">\n    <\/div>\n<!-- \/module divider -->\n        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column sub_column col4-1 tb_j61g549 last\">\n                    <!-- module image -->\n<div  class=\"module module-image tb_rr0z549 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/diatip.com\/wp-content\/uploads\/2015\/02\/Accessories-new.jpg\" width=\"300\" height=\"250\" title=\"Accueil\" alt=\"Accueil\">    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                    <\/div>\n                <\/div>\n                        <\/div>\n        <\/div>\n            <\/div>\n<!--\/themify_builder_content--><\/div>\n<\/div>\n<!-- \/module template_part -->        <\/div>\n                    <\/div>\n        <!-- module divider -->\n<div  class=\"module tf_mw module-divider tb_yazf945 solid   \" style=\"border-width: 1px;border-color: rgba(255,255,255, 0.00);margin-top: 30px;margin-bottom: 30px;\" data-lazy=\"1\">\n    <\/div>\n<!-- \/module divider -->\n        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-css_id=\"5wst934\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth_row_container tb_5wst934 tf_w\">\n            <span class=\"tb_row_frame_wrap tf_overflow tf_abs\" data-lazy=\"1\"><span class=\"tb_row_frame tb_row_frame_bottom  tf_abs tf_hide tf_overflow tf_w\"><\/span><\/span>            <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_r01x945 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_l2qw945   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h2 style=\"text-align: center;\">The Diatip\u2122 Advantages<\/h2>    <\/div>\n<\/div>\n<!-- \/module text -->        <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_2 tb_tu1o945\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column col4-2 tb_xjye946 first\">\n                    <!-- module feature -->\n<div  class=\"module module-feature tb_2uth946 with-chart layout-icon-top size-small \" data-layout-mobile=\"icon-top\" data-layout-desktop=\"icon-top\" data-lazy=\"1\">\n        <div class=\"module-feature-image tf_textc tf_rel\">\n                            <span class=\"module-feature-chart-html5 tf_box tf_rel tf_inline_b\">\n                                    <svg class=\"tf_abs tf_w tf_h\">\n                    <circle class=\"tb_feature_fill\" r=\"calc(50% - 1.00px)\" cx=\"50%\" cy=\"50%\" stroke-width=\"2\"\/>\n                    <circle class=\"tb_feature_stroke\" r=\"calc(50% - 1.00px)\" cx=\"50%\" cy=\"50%\" stroke=\"#070498\" stroke-width=\"2\" data-progress=\"100\" stroke-dasharray=\"0,10000\"\/>\n                                        <\/svg>\n                                <span class=\"chart-html5-circle tf_w tf_h\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/diatip.com\/wp-content\/uploads\/2020\/09\/1.fast-easy.jpg\" width=\"100\" height=\"100\" style=\"width:calc(100% - 4px);height:calc(100% - 4px)\" alt=\"Fast and easy to operate\">                                    <\/span>\n\n                \n            <\/span>\n                <\/div>\n    <div class=\"module-feature-content tf_textc\">\n                    <h3 class=\"module-feature-title\">\n                            Fast and easy to operate                        <\/h3>\n                    <div class=\"tb_text_wrap\">\n            <p>Works without noise or scrap<\/p>        <\/div>\n    <\/div>\n<\/div>\n<!-- \/module feature -->\n        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column sub_column col4-2 tb_hzrn946 last\">\n                    <!-- module feature -->\n<div  class=\"module module-feature tb_wtoi946 with-chart layout-icon-top size-small \" data-layout-mobile=\"icon-top\" data-layout-desktop=\"icon-top\" data-lazy=\"1\">\n        <div class=\"module-feature-image tf_textc tf_rel\">\n                            <span class=\"module-feature-chart-html5 tf_box tf_rel tf_inline_b\">\n                                    <svg class=\"tf_abs tf_w tf_h\">\n                    <circle class=\"tb_feature_fill\" r=\"calc(50% - 1.00px)\" cx=\"50%\" cy=\"50%\" stroke-width=\"2\"\/>\n                    <circle class=\"tb_feature_stroke\" r=\"calc(50% - 1.00px)\" cx=\"50%\" cy=\"50%\" stroke=\"#070498\" stroke-width=\"2\" data-progress=\"100\" stroke-dasharray=\"0,10000\"\/>\n                                        <\/svg>\n                                <span class=\"chart-html5-circle tf_w tf_h\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2025\/05\/2.chose_new_-100x100.jpg\" width=\"100\" height=\"100\" class=\"wp-post-image wp-image-2026\" title=\"2.chose_new_\" style=\"width:calc(100% - 4px);height:calc(100% - 4px)\" alt=\"Chose any number of segments\" srcset=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2025\/05\/2.chose_new_-100x100.jpg 100w, https:\/\/www.diatip.com\/wp-content\/uploads\/2025\/05\/2.chose_new_-300x300.jpg 300w, https:\/\/www.diatip.com\/wp-content\/uploads\/2025\/05\/2.chose_new_-150x150.jpg 150w, https:\/\/www.diatip.com\/wp-content\/uploads\/2025\/05\/2.chose_new_.jpg 410w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/>                                    <\/span>\n\n                \n            <\/span>\n                <\/div>\n    <div class=\"module-feature-content tf_textc\">\n                    <h3 class=\"module-feature-title\">\n                            Chose any number of segments                        <\/h3>\n                    <div class=\"tb_text_wrap\">\n            <p>Perfect segment division<\/p>        <\/div>\n    <\/div>\n<\/div>\n<!-- \/module feature -->\n        <\/div>\n                    <\/div>\n                <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_2 tb_58wj946\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column col4-2 tb_q3b0946 first\">\n                    <!-- module feature -->\n<div  class=\"module module-feature tb_6htn947 with-chart layout-icon-top size-small \" data-layout-mobile=\"icon-top\" data-layout-desktop=\"icon-top\" data-lazy=\"1\">\n        <div class=\"module-feature-image tf_textc tf_rel\">\n                            <span class=\"module-feature-chart-html5 tf_box tf_rel tf_inline_b\">\n                                    <svg class=\"tf_abs tf_w tf_h\">\n                    <circle class=\"tb_feature_fill\" r=\"calc(50% - 1.00px)\" cx=\"50%\" cy=\"50%\" stroke-width=\"2\"\/>\n                    <circle class=\"tb_feature_stroke\" r=\"calc(50% - 1.00px)\" cx=\"50%\" cy=\"50%\" stroke=\"#070498\" stroke-width=\"2\" data-progress=\"100\" stroke-dasharray=\"0,10000\"\/>\n                                        <\/svg>\n                                <span class=\"chart-html5-circle tf_w tf_h\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2025\/05\/3.cuts-slots-new-100x100.jpg\" width=\"100\" height=\"100\" class=\"wp-post-image wp-image-2030\" title=\"3.cuts-slots-new\" style=\"width:calc(100% - 4px);height:calc(100% - 4px)\" alt=\"Cuts slots for the segments\" srcset=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2025\/05\/3.cuts-slots-new-100x100.jpg 100w, https:\/\/www.diatip.com\/wp-content\/uploads\/2025\/05\/3.cuts-slots-new-300x300.jpg 300w, https:\/\/www.diatip.com\/wp-content\/uploads\/2025\/05\/3.cuts-slots-new-150x150.jpg 150w, https:\/\/www.diatip.com\/wp-content\/uploads\/2025\/05\/3.cuts-slots-new.jpg 410w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/>                                    <\/span>\n\n                \n            <\/span>\n                <\/div>\n    <div class=\"module-feature-content tf_textc\">\n                    <h3 class=\"module-feature-title\">\n                            Cuts slots for the segments                        <\/h3>\n                    <div class=\"tb_text_wrap\">\n            <p>Easier to position and braze the segments<\/p>        <\/div>\n    <\/div>\n<\/div>\n<!-- \/module feature -->\n        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column sub_column col4-2 tb_08h4947 last\">\n                    <!-- module feature -->\n<div  class=\"module module-feature tb_bwfc947 with-chart layout-icon-top size-small \" data-layout-mobile=\"icon-top\" data-layout-desktop=\"icon-top\" data-lazy=\"1\">\n        <div class=\"module-feature-image tf_textc tf_rel\">\n                            <span class=\"module-feature-chart-html5 tf_box tf_rel tf_inline_b\">\n                                    <svg class=\"tf_abs tf_w tf_h\">\n                    <circle class=\"tb_feature_fill\" r=\"calc(50% - 1.00px)\" cx=\"50%\" cy=\"50%\" stroke-width=\"2\"\/>\n                    <circle class=\"tb_feature_stroke\" r=\"calc(50% - 1.00px)\" cx=\"50%\" cy=\"50%\" stroke=\"#070498\" stroke-width=\"2\" data-progress=\"100\" stroke-dasharray=\"0,10000\"\/>\n                                        <\/svg>\n                                <span class=\"chart-html5-circle tf_w tf_h\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/diatip.com\/wp-content\/uploads\/2020\/09\/4.makes-stronger.jpg\" width=\"100\" height=\"100\" style=\"width:calc(100% - 4px);height:calc(100% - 4px)\" alt=\"Makes the whole bit stronger\">                                    <\/span>\n\n                \n            <\/span>\n                <\/div>\n    <div class=\"module-feature-content tf_textc\">\n                    <h3 class=\"module-feature-title\">\n                            Makes the whole bit stronger                        <\/h3>\n                    <div class=\"tb_text_wrap\">\n            <p>Flexibility in manufacturing<\/p>        <\/div>\n    <\/div>\n<\/div>\n<!-- \/module feature -->\n        <\/div>\n                    <\/div>\n                <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_6jpb934 tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_2 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col4-2 tb_wvwp947 first\">\n                    <!-- module feature -->\n<div  class=\"module module-feature tb_wb9v947 no-chart layout-icon-left size-custom \" data-layout-mobile=\"icon-top\" data-layout-desktop=\"icon-left\" data-lazy=\"1\">\n        <div class=\"module-feature-image tf_textc tf_rel\">\n                            <span class=\"module-feature-chart-html5 tf_box tf_rel tf_inline_b\" style=\"width:120px;height:120px;\">\n                                <span class=\"chart-html5-circle tf_w tf_h\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2014\/07\/carina-hemsida-120x120.jpg\" width=\"120\" height=\"120\" class=\"wp-post-image wp-image-1064\" title=\"carina-hemsida\" style=\"width:calc(100% - 0px);height:calc(100% - 0px)\" alt=\"Carina Midhage\">                                    <\/span>\n\n                \n            <\/span>\n                <\/div>\n    <div class=\"module-feature-content tf_textc\">\n                    <h3 class=\"module-feature-title\">\n                            Carina Midhage                        <\/h3>\n                    <div class=\"tb_text_wrap\">\n            <h4>Ventes et assistance<\/h4>\n<p><span style=\"color: #000000\"><strong>Midhage Diatip AB<\/strong><\/span><br><span style=\"color: #000000\">Miraall\u00e9n 41<\/span><br><span style=\"color: #000000\">SE-417 58\u00a0G\u00f6teborg<\/span><br><span style=\"color: #000000\">Sweden<\/span><\/p>\n<p><span style=\"color: #000000\"><strong>Tel.<\/strong> \u00a0+46 431 75650<\/span><br><span style=\"color: #000000\"><strong>Tel.<\/strong> \u00a0+46 706 844 999<\/span><br><span style=\"color: #000000\"><strong>Email.<\/strong>\u00a0midhage@diatip.com<\/span><\/p>        <\/div>\n    <\/div>\n<\/div>\n<!-- \/module feature -->\n        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column tb-column col4-2 tb_daj6948 last\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_uu45948   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h4>T\u00c9L\u00c9CHARGER NOTRE BROCHURE<\/h4>\n<div id=\"brochures\"><a href=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2014\/06\/DT-0101-Eng-net.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-202 alignleft\" src=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2014\/06\/United-Kingdom.png\" alt=\"United-Kingdom\" width=\"50\" height=\"34\"><\/a><a href=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2014\/06\/DT-0101-Fr-net.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-201 alignleft\" src=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2014\/06\/France.png\" alt=\"France\" width=\"50\" height=\"34\"><\/a><a href=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2014\/06\/DT-0101-Ty-net.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-200 alignleft\" src=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2014\/06\/Germany.png\" alt=\"Germany\" width=\"50\" height=\"34\"><\/a><a href=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2014\/06\/DT-0101-Sp-net.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-199 alignleft\" src=\"https:\/\/www.diatip.com\/wp-content\/uploads\/2014\/06\/Spain.png\" alt=\"Spain\" width=\"50\" height=\"34\"><\/a><\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->","protected":false},"excerpt":{"rendered":"<p>Diatip\u2122 has everything you need for a successful re-tipping work: Equipment, Brazing Magnets, Auxiliaries and Instructions.\u00a0 Bienvenue sur Diatip Diatip a tout ce dont vous avez besoin pour une r\u00e9paration de pointe r\u00e9ussie : \u00e9quipements, aimants de brasage, auxiliaires et instructions. Plus de 30 ans d&rsquo;exp\u00e9rience dans les \u00e9quipements de r\u00e9paration de pointe des couronnes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-818","page","type-page","status-publish","hentry","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accueil &#8226; Diatip<\/title>\n<meta name=\"description\" content=\"Diatip\u2122 has everything you need for a successful re-tipping work: Equipment, Brazing Magnets, Auxiliaries and Instructions.\u00a0 Bienvenue sur Diatip Diatip a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diatip.com\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accueil &#8226; Diatip\" \/>\n<meta property=\"og:description\" content=\"Diatip\u2122 has everything you need for a successful re-tipping work: Equipment, Brazing Magnets, Auxiliaries and Instructions.\u00a0 Bienvenue sur Diatip Diatip a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diatip.com\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Diatip\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T08:58:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diatip.com\/wp-content\/uploads\/2020\/09\/1.fast-easy.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/\",\"url\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/\",\"name\":\"Accueil &#8226; Diatip\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diatip.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/1.fast-easy.jpg\",\"datePublished\":\"2020-09-24T09:23:15+00:00\",\"dateModified\":\"2025-05-21T08:58:59+00:00\",\"description\":\"Diatip\u2122 has everything you need for a successful re-tipping work: Equipment, Brazing Magnets, Auxiliaries and Instructions.\u00a0 Bienvenue sur Diatip Diatip a\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diatip.com\\\/fr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diatip.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/1.fast-easy.jpg\",\"contentUrl\":\"https:\\\/\\\/diatip.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/1.fast-easy.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/\",\"name\":\"Diatip\",\"description\":\"Retipping Diamond Core Bits or Diamond Sawblades\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/#organization\",\"name\":\"Diatip\",\"url\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diatip.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/diatip-logo-low.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diatip.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/diatip-logo-low.jpg\",\"width\":304,\"height\":92,\"caption\":\"Diatip\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diatip.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil &#8226; Diatip","description":"Diatip\u2122 has everything you need for a successful re-tipping work: Equipment, Brazing Magnets, Auxiliaries and Instructions.\u00a0 Bienvenue sur Diatip Diatip a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diatip.com\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Accueil &#8226; Diatip","og_description":"Diatip\u2122 has everything you need for a successful re-tipping work: Equipment, Brazing Magnets, Auxiliaries and Instructions.\u00a0 Bienvenue sur Diatip Diatip a","og_url":"https:\/\/www.diatip.com\/fr\/","og_site_name":"Diatip","article_modified_time":"2025-05-21T08:58:59+00:00","og_image":[{"url":"https:\/\/diatip.com\/wp-content\/uploads\/2020\/09\/1.fast-easy.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.diatip.com\/fr\/","url":"https:\/\/www.diatip.com\/fr\/","name":"Accueil &#8226; Diatip","isPartOf":{"@id":"https:\/\/www.diatip.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diatip.com\/fr\/#primaryimage"},"image":{"@id":"https:\/\/www.diatip.com\/fr\/#primaryimage"},"thumbnailUrl":"https:\/\/diatip.com\/wp-content\/uploads\/2020\/09\/1.fast-easy.jpg","datePublished":"2020-09-24T09:23:15+00:00","dateModified":"2025-05-21T08:58:59+00:00","description":"Diatip\u2122 has everything you need for a successful re-tipping work: Equipment, Brazing Magnets, Auxiliaries and Instructions.\u00a0 Bienvenue sur Diatip Diatip a","breadcrumb":{"@id":"https:\/\/www.diatip.com\/fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diatip.com\/fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.diatip.com\/fr\/#primaryimage","url":"https:\/\/diatip.com\/wp-content\/uploads\/2020\/09\/1.fast-easy.jpg","contentUrl":"https:\/\/diatip.com\/wp-content\/uploads\/2020\/09\/1.fast-easy.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.diatip.com\/fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.diatip.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/www.diatip.com\/fr\/#website","url":"https:\/\/www.diatip.com\/fr\/","name":"Diatip","description":"Retipping Diamond Core Bits or Diamond Sawblades","publisher":{"@id":"https:\/\/www.diatip.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diatip.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.diatip.com\/fr\/#organization","name":"Diatip","url":"https:\/\/www.diatip.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.diatip.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.diatip.com\/wp-content\/uploads\/2020\/06\/diatip-logo-low.jpg","contentUrl":"https:\/\/www.diatip.com\/wp-content\/uploads\/2020\/06\/diatip-logo-low.jpg","width":304,"height":92,"caption":"Diatip"},"image":{"@id":"https:\/\/www.diatip.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.diatip.com\/fr\/wp-json\/wp\/v2\/pages\/818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diatip.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.diatip.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.diatip.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diatip.com\/fr\/wp-json\/wp\/v2\/comments?post=818"}],"version-history":[{"count":41,"href":"https:\/\/www.diatip.com\/fr\/wp-json\/wp\/v2\/pages\/818\/revisions"}],"predecessor-version":[{"id":2049,"href":"https:\/\/www.diatip.com\/fr\/wp-json\/wp\/v2\/pages\/818\/revisions\/2049"}],"wp:attachment":[{"href":"https:\/\/www.diatip.com\/fr\/wp-json\/wp\/v2\/media?parent=818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}